{"id":63901,"date":"2026-07-15T16:46:52","date_gmt":"2026-07-15T19:46:52","guid":{"rendered":"https:\/\/anprotec.org.br\/site\/?p=63901"},"modified":"2026-07-15T16:47:03","modified_gmt":"2026-07-15T19:47:03","slug":"anprotec-participa-da-fetech-e-do-xx-encontro-nacional-fortec-2026","status":"publish","type":"post","link":"https:\/\/anprotec.org.br\/site\/2026\/07\/anprotec-participa-da-fetech-e-do-xx-encontro-nacional-fortec-2026\/","title":{"rendered":"Anprotec participa da FETECH e do XX Encontro Nacional FORTEC 2026"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">A diretora de Redes e Associados da Anprotec, Ma\u00edra Nobre, representou a Associa\u00e7\u00e3o nesta semana em dois importantes eventos voltados \u00e0 inova\u00e7\u00e3o, ao empreendedorismo e ao desenvolvimento tecnol\u00f3gico, realizados em Campina Grande (PB): a 15\u00aa FETECH \u2013 Feira Tecnol\u00f3gica de Campina Grande e o XX Encontro Nacional FORTEC 2026. As participa\u00e7\u00f5es refor\u00e7aram a atua\u00e7\u00e3o da Anprotec na promo\u00e7\u00e3o da inova\u00e7\u00e3o, da transfer\u00eancia de tecnologia e da articula\u00e7\u00e3o entre universidades, ambientes de inova\u00e7\u00e3o e mercado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na <\/span><b>FETECH<\/b><span style=\"font-weight: 400;\">, o debate abordou as compet\u00eancias necess\u00e1rias para a constru\u00e7\u00e3o de carreiras globais e para a promo\u00e7\u00e3o da transforma\u00e7\u00e3o social:\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201c<\/span><b>Falamos sobre as mudan\u00e7as no mundo do trabalho impulsionadas pela intelig\u00eancia artificial, pela transforma\u00e7\u00e3o digital e pela internacionaliza\u00e7\u00e3o da economia; a import\u00e2ncia de desenvolver compet\u00eancias t\u00e9cnicas e socioemocionais, construir uma trajet\u00f3ria profissional com prop\u00f3sito e comunicar, de forma estrat\u00e9gica, compet\u00eancias, valores e resultados.<\/b><span style=\"font-weight: 400;\">\u201d<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tamb\u00e9m foram apresentadas estrat\u00e9gias para a internacionaliza\u00e7\u00e3o de carreiras, como a participa\u00e7\u00e3o em iniciativas nacionais e internacionais de pesquisa e inova\u00e7\u00e3o, o dom\u00ednio de idiomas e a organiza\u00e7\u00e3o de portf\u00f3lios capazes de evidenciar compet\u00eancias e experi\u00eancias profissionais.<\/span><\/p>\n<div class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" class=\"wpa-warning wpa-image-missing-alt wp-image-63903 aligncenter\" src=\"https:\/\/anprotec.org.br\/site\/wp-content\/uploads\/2026\/07\/PHOTO-2026-07-14-16-43-55-300x200.jpg\" alt=\"\" width=\"695\" height=\"463\" data-warning=\"Missing alt text\" srcset=\"https:\/\/anprotec.org.br\/site\/wp-content\/uploads\/2026\/07\/PHOTO-2026-07-14-16-43-55-300x200.jpg 300w, https:\/\/anprotec.org.br\/site\/wp-content\/uploads\/2026\/07\/PHOTO-2026-07-14-16-43-55-1024x682.jpg 1024w, https:\/\/anprotec.org.br\/site\/wp-content\/uploads\/2026\/07\/PHOTO-2026-07-14-16-43-55-768x512.jpg 768w, https:\/\/anprotec.org.br\/site\/wp-content\/uploads\/2026\/07\/PHOTO-2026-07-14-16-43-55-219x146.jpg 219w, https:\/\/anprotec.org.br\/site\/wp-content\/uploads\/2026\/07\/PHOTO-2026-07-14-16-43-55-50x33.jpg 50w, https:\/\/anprotec.org.br\/site\/wp-content\/uploads\/2026\/07\/PHOTO-2026-07-14-16-43-55-113x75.jpg 113w, https:\/\/anprotec.org.br\/site\/wp-content\/uploads\/2026\/07\/PHOTO-2026-07-14-16-43-55.jpg 1280w\" sizes=\"(max-width: 695px) 100vw, 695px\" \/><\/div>\n<p><span style=\"font-weight: 400;\">Na sexta-feira (10), Ma\u00edra tamb\u00e9m participou do painel <\/span><b>\u201cSpin-offs Acad\u00eamicas: Empreendedorismo por Design\u201d<\/b><span style=\"font-weight: 400;\">, durante o XX Encontro Nacional FORTEC 2026. Moderado por Celeste Emerick, conselheira consultiva do FORTEC, o painel reuniu especialistas para debater estrat\u00e9gias de transforma\u00e7\u00e3o da pesquisa cient\u00edfica em neg\u00f3cios inovadores, fortalecendo a cria\u00e7\u00e3o de spin-offs acad\u00eamicas e startups de base tecnol\u00f3gica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m de Ma\u00edra, participaram do painel Iara Regina da Silva Ferreira, da Inova Unicamp, e outros especialistas que discutiram m\u00e9todos para acelerar a transforma\u00e7\u00e3o das atividades de ensino, pesquisa e extens\u00e3o em neg\u00f3cios inovadores, com destaque para pr\u00e1ticas como alfabetiza\u00e7\u00e3o empreendedora, hackathons, matchmaking, redes de mentoria e programas de soft landing.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Representando a Anprotec, Ma\u00edra destacou que o fortalecimento das spin-offs acad\u00eamicas depende da integra\u00e7\u00e3o entre os diferentes atores do ecossistema de inova\u00e7\u00e3o.<\/span><\/p>\n<p><b>\u201cAs spin-offs acad\u00eamicas s\u00e3o resultado de uma jornada que depende da atua\u00e7\u00e3o articulada de diferentes institui\u00e7\u00f5es. O FORTEC e a Anprotec exercem pap\u00e9is complementares nesse processo: enquanto os N\u00facleos de Inova\u00e7\u00e3o Tecnol\u00f3gica apoiam a prote\u00e7\u00e3o e a transfer\u00eancia do conhecimento gerado nas institui\u00e7\u00f5es de pesquisa, os ambientes de inova\u00e7\u00e3o oferecem as condi\u00e7\u00f5es para que essas tecnologias evoluam, atraiam empreendedores, investidores e parceiros e alcancem o mercado. \u00c9 dessa conex\u00e3o entre ci\u00eancia, empreendedorismo e inova\u00e7\u00e3o que surgem neg\u00f3cios capazes de gerar desenvolvimento econ\u00f4mico e impacto para a sociedade.\u201d<\/b><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wpa-warning wpa-image-missing-alt wp-image-63902 aligncenter\" src=\"https:\/\/anprotec.org.br\/site\/wp-content\/uploads\/2026\/07\/PHOTO-2026-07-10-09-35-39-1-300x169.jpg\" alt=\"\" width=\"699\" height=\"394\" data-warning=\"Missing alt text\" srcset=\"https:\/\/anprotec.org.br\/site\/wp-content\/uploads\/2026\/07\/PHOTO-2026-07-10-09-35-39-1-300x169.jpg 300w, https:\/\/anprotec.org.br\/site\/wp-content\/uploads\/2026\/07\/PHOTO-2026-07-10-09-35-39-1-1024x576.jpg 1024w, https:\/\/anprotec.org.br\/site\/wp-content\/uploads\/2026\/07\/PHOTO-2026-07-10-09-35-39-1-768x432.jpg 768w, https:\/\/anprotec.org.br\/site\/wp-content\/uploads\/2026\/07\/PHOTO-2026-07-10-09-35-39-1-1536x864.jpg 1536w, https:\/\/anprotec.org.br\/site\/wp-content\/uploads\/2026\/07\/PHOTO-2026-07-10-09-35-39-1-260x146.jpg 260w, https:\/\/anprotec.org.br\/site\/wp-content\/uploads\/2026\/07\/PHOTO-2026-07-10-09-35-39-1-50x28.jpg 50w, https:\/\/anprotec.org.br\/site\/wp-content\/uploads\/2026\/07\/PHOTO-2026-07-10-09-35-39-1-133x75.jpg 133w, https:\/\/anprotec.org.br\/site\/wp-content\/uploads\/2026\/07\/PHOTO-2026-07-10-09-35-39-1-1200x675.jpg 1200w, https:\/\/anprotec.org.br\/site\/wp-content\/uploads\/2026\/07\/PHOTO-2026-07-10-09-35-39-1.jpg 1599w\" sizes=\"(max-width: 699px) 100vw, 699px\" \/><\/p>\n<div class=\"wp-block-image\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A diretora de Redes e Associados da Anprotec, Ma\u00edra Nobre,<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":21,"featured_media":63904,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3],"tags":[],"calendar":[],"_links":{"self":[{"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/posts\/63901"}],"collection":[{"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/comments?post=63901"}],"version-history":[{"count":2,"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/posts\/63901\/revisions"}],"predecessor-version":[{"id":63906,"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/posts\/63901\/revisions\/63906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/media\/63904"}],"wp:attachment":[{"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/media?parent=63901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/categories?post=63901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/tags?post=63901"},{"taxonomy":"calendar","embeddable":true,"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/calendar?post=63901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}