{"id":3919,"date":"2013-08-29T10:21:45","date_gmt":"2013-08-29T13:21:45","guid":{"rendered":"http:\/\/anprotec.org.br\/site\/?p=3919"},"modified":"2013-08-29T10:22:31","modified_gmt":"2013-08-29T13:22:31","slug":"iagram-abre-processo-seletivo-de-empresas","status":"publish","type":"post","link":"https:\/\/anprotec.org.br\/site\/2013\/08\/iagram-abre-processo-seletivo-de-empresas\/","title":{"rendered":"<!--:pt-->Iagram abre processo seletivo de empresas<!--:-->"},"content":{"rendered":"<p><!--:pt--><\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-3920\" alt=\"topo blog\" src=\"https:\/\/anprotec.org.br\/site\/wp-content\/uploads\/2013\/08\/topo-blog-300x89.jpg\" width=\"300\" height=\"89\" srcset=\"https:\/\/anprotec.org.br\/site\/wp-content\/uploads\/2013\/08\/topo-blog-300x89.jpg 300w, https:\/\/anprotec.org.br\/site\/wp-content\/uploads\/2013\/08\/topo-blog.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>A \u00a0<a href=\"http:\/\/iagramrn.com.br\/\">Iagram<\/a>, Incubadora Tecnol\u00f3gica e do Agroneg\u00f3cio de Mossor\u00f3 (RN), est\u00e1 com dois editais abertos para sele\u00e7\u00e3o de empreendimentos. Um deles \u00e9 voltado para empresas que atuam na \u00e1rea de agroneg\u00f3cio. O outro, para empreendimentos de base tecnol\u00f3gica. \u00a0A Iagram oferece, em cada um dos editais, quatro vagas para pr\u00e9-incuba\u00e7\u00e3o e tr\u00eas vagas para incuba\u00e7\u00e3o &#8211; duas vagas para empreendimentos n\u00e3o-residentes e uma para residente. Os interessados em participar t\u00eam at\u00e9 o dia 13 de setembro para se inscrever.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Acesse o <a href=\"http:\/\/iagramrn.com.br\/wp-content\/uploads\/2013\/08\/EDITAL-PADR%C3%83O-IAGRAM-AGRONEG%C3%93CIO-01.pdf\">edital para o agroneg\u00f3cio<\/a> e o <a href=\"http:\/\/iagramrn.com.br\/wp-content\/uploads\/2013\/08\/EDITAL-PADR%C3%83O-IAGRAM-BASE-TECNOL%C3%93GICA-01.pdf\">edital para empresas de tecnologia<\/a>.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Os editais s\u00e3o voltados para alunos de gradua\u00e7\u00e3o e p\u00f3s-gradua\u00e7\u00e3o da Universidade Federal Rural do Semi-\u00c1rido (Ufersa), servidores p\u00fablicos, pesquisadores ou empreendedores da iniciativa privada que pretendem consolidar uma ideia ou atividade comercial. Para concorrer, deve-se apresentar uma proposta de trabalho e um plano de neg\u00f3cios. No ato da entrega dos documentos \u00e9 cobrada uma taxa de R$ 25,00 para pr\u00e9-incuba\u00e7\u00e3o e de R$ 50,00 para incuba\u00e7\u00e3o.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">A divulga\u00e7\u00e3o do resultado final dos empreendimentos selecionados est\u00e1 prevista para o pr\u00f3ximo dia 7 de outubro.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\"><em>*Com informa\u00e7\u00f5es da Ufersa<\/em><\/p>\n<p><!--:--><\/p>\n","protected":false},"excerpt":{"rendered":"<p><!--:pt-->A Incubadora Tecnol\u00f3gica e do Agroneg\u00f3cio de Mossor\u00f3 seleciona empreendimentos ligados ao agroneg\u00f3cio e a tecnologia. S\u00e3o 14 vagas divididas entre incuba\u00e7\u00e3o e pr\u00e9-incuba\u00e7\u00e3o.<!--:--><\/p>\n","protected":false},"author":8,"featured_media":2436,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3],"tags":[],"calendar":[],"_links":{"self":[{"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/posts\/3919"}],"collection":[{"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/comments?post=3919"}],"version-history":[{"count":2,"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/posts\/3919\/revisions"}],"predecessor-version":[{"id":3922,"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/posts\/3919\/revisions\/3922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/media\/2436"}],"wp:attachment":[{"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/media?parent=3919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/categories?post=3919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/tags?post=3919"},{"taxonomy":"calendar","embeddable":true,"href":"https:\/\/anprotec.org.br\/site\/wp-json\/wp\/v2\/calendar?post=3919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}